{"id":1209,"date":"2019-03-29T12:42:56","date_gmt":"2019-03-29T11:42:56","guid":{"rendered":"https:\/\/2019.irun.wordcamp.org\/?post_type=wcb_sponsor&#038;p=1209"},"modified":"2019-04-02T12:41:00","modified_gmt":"2019-04-02T10:41:00","slug":"webempresa","status":"publish","type":"wcb_sponsor","link":"https:\/\/irun.wordcamp.org\/2019\/sponsor\/webempresa\/","title":{"rendered":"Webempresa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tienes muchas cosas que contar y nosotros te ayudaremos a enviar tu mensaje al mundo \ud83d\ude42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos hablarte de las maravillas t\u00e9cnicas de nuestros servidores, pero de lo que realmente estamos orgullosos es de nuestro equipo. Somos fan\u00e1ticos de WordPress y nos encanta tener clientes contentos y felices.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Nos tienes disponibles 24 horas, todos los d\u00edas del a\u00f1o listos para ayudarte a resolver los problemas y dudas con tu Hosting.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reglas de seguridad Anti-hackeo especiales para WordPress, auditor\u00edas de seguridad autom\u00e1ticas gratuitas y bloqueo de los pesados de los spammers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos un&nbsp;<a href=\"https:\/\/www.webempresa.com\/wordpress\/hosting-wordpress.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">hosting para WordPress<\/a>&nbsp;pensado para que tu web vuele y Google se lo coma a besos: Certificados SSL gratuitos, servidores con discos SSD, sistema de cach\u00e9 propio a nivel servidor, servicio de optimizaci\u00f3n gratuita de im\u00e1genes, etc&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s hemos desarrollado herramientas gratuitas para WordPress como <a href=\"http:\/\/llavero.io\/\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener nofollow\">llavero.io<\/a>&nbsp;(un plugin gratuito que te aporta un extra de seguridad en los accesos a tu web), <a aria-label=\"Optimizador.io (opens in a new tab)\" href=\"https:\/\/optimizador.io\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Optimizador.io<\/a> (un plugin para optimizar las im\u00e1genes de tu web autom\u00e1ticamente y que te ayuda con el posicionamiento SEO), <a aria-label=\"WP Center (opens in a new tab)\" href=\"https:\/\/www.webempresa.com\/blog\/wpcenter-para-wordpress-centraliza-la-gestion-de-tus-webs.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">WP Center<\/a> (un centro de mandos para mantener actualizadas las webs WordPress y plugins de forma autom\u00e1tica con una configuraci\u00f3n muy sencilla y r\u00e1pida) y <a aria-label=\"SuperBackUp (opens in a new tab)\" href=\"https:\/\/www.webempresa.com\/blog\/copias-seguridad-superbackup-cpanel-dominalas.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">SuperBackUp<\/a> (un sistema de copias de seguridad para restaurar versiones anteriores de tu web de los \u00faltimos 30 d\u00edas desde el \u00e1rea de cliente). An\u00edmate a probarlas y a contarnos que te parecen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 un placer alojar tu Web en casa \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tienes muchas cosas que contar y nosotros te ayudaremos a enviar tu mensaje al mundo \ud83d\ude42 Podemos hablarte de las maravillas t\u00e9cnicas de nuestros servidores, pero de lo que realmente estamos orgullosos es de nuestro equipo. Somos fan\u00e1ticos de WordPress &hellip; <a href=\"https:\/\/irun.wordcamp.org\/2019\/sponsor\/webempresa\/\">Seguir leyendo <span class=\"screen-reader-text\">Webempresa<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"featured_media":1210,"template":"","meta":{"_wcpt_sponsor_website":"https:\/\/www.webempresa.com","footnotes":""},"sponsor_level":[10619],"class_list":["post-1209","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-bronce"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheIBw-jv","_links":{"self":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sponsors\/1209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":4,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sponsors\/1209\/revisions"}],"predecessor-version":[{"id":1267,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sponsors\/1209\/revisions\/1267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/media\/1210"}],"wp:attachment":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=1209"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sponsor_level?post=1209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}