{"id":944,"date":"2019-03-24T08:17:23","date_gmt":"2019-03-24T07:17:23","guid":{"rendered":"https:\/\/2019.irun.wordcamp.org\/?post_type=wcb_session&#038;p=944"},"modified":"2019-06-03T10:20:36","modified_gmt":"2019-06-03T08:20:36","slug":"por-que-deberias-redactar-entradas-de-blog-perfectas-y-como-hacerlo","status":"publish","type":"wcb_session","link":"https:\/\/irun.wordcamp.org\/2019\/session\/por-que-deberias-redactar-entradas-de-blog-perfectas-y-como-hacerlo\/","title":{"rendered":"Por qu\u00e9 deber\u00edas redactar entradas de blog perfectas y c\u00f3mo hacerlo"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2019.irun.wordcamp.org\/files\/2019\/03\/20_FERNANDO-TELLADO-1024x512.jpg\" alt=\"\" class=\"wp-image-1744\" srcset=\"https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/20_FERNANDO-TELLADO.jpg 1024w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/20_FERNANDO-TELLADO-300x150.jpg 300w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/20_FERNANDO-TELLADO-768x384.jpg 768w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/20_FERNANDO-TELLADO-500x250.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En esta ponencia te resumir\u00e9 de manera que puedas aplicar de inmediato lo que he aprendido los \u00faltimos m\u00e1s de 10 a\u00f1os sobre c\u00f3mo crear entradas de blog perfectas para obtener el m\u00e1ximo rendimiento de tr\u00e1fico, viralidad y SEO con las herramientas que nos ofrece WordPress.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta ponencia te resumir\u00e9 de manera que puedas aplicar de inmediato lo que he aprendido los \u00faltimos m\u00e1s de 10 a\u00f1os sobre c\u00f3mo crear entradas de blog perfectas para obtener el m\u00e1ximo rendimiento de tr\u00e1fico, viralidad y SEO con &hellip; <a href=\"https:\/\/irun.wordcamp.org\/2019\/session\/por-que-deberias-redactar-entradas-de-blog-perfectas-y-como-hacerlo\/\">Seguir leyendo <span class=\"screen-reader-text\">Por qu\u00e9 deber\u00edas redactar entradas de blog perfectas y c\u00f3mo hacerlo<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1320655,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1559397000,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"https:\/\/2019.irun.wordcamp.org\/files\/2019\/06\/fernando-tellado-por-que-deberias-redactar-entradas-de-blog-perfectas-y-como-hacerlo-fernando-tellado.pdf","_wcpt_session_video":"","_wcpt_speaker_id":[941],"footnotes":""},"session_track":[446658],"session_category":[1226850],"class_list":["post-944","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-track-a","wcb_session_category-contenidos"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheIBw-fe","session_date_time":{"date":"01\/06\/2019","time":"15:50"},"session_speakers":[{"id":"941","slug":"fernando-tellado","name":"Fernando Tellado","link":"https:\/\/irun.wordcamp.org\/2019\/speaker\/fernando-tellado\/"}],"session_cats_rendered":"Contenidos","_links":{"self":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":2,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/944\/revisions"}],"predecessor-version":[{"id":1769,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/944\/revisions\/1769"}],"speakers":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/941"}],"author":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wporg\/v1\/users\/fernandot"}],"wp:attachment":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=944"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_track?post=944"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_category?post=944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}