{"id":1042,"date":"2019-03-24T17:15:47","date_gmt":"2019-03-24T16:15:47","guid":{"rendered":"https:\/\/2019.irun.wordcamp.org\/?post_type=wcb_session&#038;p=1042"},"modified":"2019-06-03T10:18:07","modified_gmt":"2019-06-03T08:18:07","slug":"y-el-dominio-que","status":"publish","type":"wcb_session","link":"https:\/\/irun.wordcamp.org\/2019\/session\/y-el-dominio-que\/","title":{"rendered":"\u00bfY el dominio qu\u00e9?"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/2019.irun.wordcamp.org\/files\/2019\/03\/22_LORENZO-OTERO-1024x512.jpg\" alt=\"\" class=\"wp-image-1742\" srcset=\"https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/22_LORENZO-OTERO.jpg 1024w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/22_LORENZO-OTERO-300x150.jpg 300w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/22_LORENZO-OTERO-768x384.jpg 768w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/03\/22_LORENZO-OTERO-500x250.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para quienes trabajamos en el mundo web, los dominios pueden parecer lo menos complejo de manejar. \u00bfBasta con que tengan unas DNS y con que apuntemos las zonas a donde nos interesa, no?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pues la verdad es que el tema va mucho m\u00e1s all\u00e1. Cada dominio sigue una normativa concreta y obligatoria para cada una de las operaciones en las que lo uses: un registro, un traslado&#8230; incluso su caducidad puede convertirse en un dolor de cabeza si no controlas bien sus plazos y procedimientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conocer la normativa de los dominios, qu\u00e9 entidades los controlan, c\u00f3mo se relacionan entre ellas y con los proveedores en los que conf\u00edas te ahorrar\u00e1 tiempo, te facilitar\u00e1 el trabajo y hasta te ayudar\u00e1 a anticipar problemas y buscar alternativas para sortearlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 van a aprender los asistentes?<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde lo m\u00e1s general a lo m\u00e1s espec\u00edfico. Primero, veremos qu\u00e9 entidades controlan el funcionamiento de los dominios y las diferencias entre ellas. Tambi\u00e9n repasaremos la normativa para el registro, traslado y caducidad de una extensi\u00f3n.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entraremos en detalle en los datos que encierra un dominio: qu\u00e9 significan, d\u00f3nde se pueden consultar y c\u00f3mo se pueden cambiar. El Reglamento General de Protecci\u00f3n de Datos (RGPD) tambi\u00e9n se aplica a este campo, por lo que te explicar\u00e9 c\u00f3mo afecta.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, trataremos algunos de los obst\u00e1culos con los que te puedes encontrar en temas de propiedad y cambios de datos de un dominio y c\u00f3mo abordalos sin morir en el intento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para quienes trabajamos en el mundo web, los dominios pueden parecer lo menos complejo de manejar. \u00bfBasta con que tengan unas DNS y con que apuntemos las zonas a donde nos interesa, no? Pues la verdad es que el tema &hellip; <a href=\"https:\/\/irun.wordcamp.org\/2019\/session\/y-el-dominio-que\/\">Seguir leyendo <span class=\"screen-reader-text\">\u00bfY el dominio qu\u00e9?<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16906086,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1559399400,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"https:\/\/2019.irun.wordcamp.org\/files\/2019\/06\/lorenzo-otero-y-el-dominio-que-irun-2019.pdf","_wcpt_session_video":"","_wcpt_speaker_id":[1043],"footnotes":""},"session_track":[446658],"session_category":[994569],"class_list":["post-1042","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-track-a","wcb_session_category-negocios"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheIBw-gO","session_date_time":{"date":"01\/06\/2019","time":"16:30"},"session_speakers":[{"id":"1043","slug":"lorenzo-otero","name":"Lorenzo Otero","link":"https:\/\/irun.wordcamp.org\/2019\/speaker\/lorenzo-otero\/"}],"session_cats_rendered":"Negocio","_links":{"self":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":4,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/1042\/revisions"}],"predecessor-version":[{"id":1765,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/1042\/revisions\/1765"}],"speakers":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/1043"}],"author":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wporg\/v1\/users\/oterogonzalez"}],"wp:attachment":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_track?post=1042"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_category?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}