{"id":1646,"date":"2019-05-17T14:21:02","date_gmt":"2019-05-17T12:21:02","guid":{"rendered":"https:\/\/2019.irun.wordcamp.org\/?p=1646"},"modified":"2019-05-23T15:44:45","modified_gmt":"2019-05-23T13:44:45","slug":"faq-para-novatos-en-wcirun","status":"publish","type":"post","link":"https:\/\/irun.wordcamp.org\/2019\/faq-para-novatos-en-wcirun\/","title":{"rendered":"FAQ para novatos en #WCIrun"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/2019.irun.wordcamp.org\/files\/2019\/05\/novatos-wordcamp-1024x683.jpg\" alt=\"\" class=\"wp-image-1650\" srcset=\"https:\/\/irun.wordcamp.org\/2019\/files\/2019\/05\/novatos-wordcamp-1024x683.jpg 1024w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/05\/novatos-wordcamp-300x200.jpg 300w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/05\/novatos-wordcamp-768x512.jpg 768w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/05\/novatos-wordcamp-450x300.jpg 450w, https:\/\/irun.wordcamp.org\/2019\/files\/2019\/05\/novatos-wordcamp.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Tres \u00abnovatos\u00bb en WordCamp Irun 2018<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ya no falta casi nada. En unos d\u00edas llega WordCamp Irun y estoy seguro de que muchos de vosotros estar\u00e9is casi tan inquietos como nosotros mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabemos que algunos os estrenar\u00e9is en una WordCamp en esta ocasi\u00f3n as\u00ed que hemos decidido publicar una peque\u00f1a FAQ con las preguntas m\u00e1s habituales que nos hac\u00e9is.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 tengo que llevar? \u00bfLlevo ordenador?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No necesitas traer nada especial<\/strong> m\u00e1s all\u00e1 de un documento acreditativo por si hay alg\u00fan problema en la recepci\u00f3n. Aqu\u00ed te daremos una bolsa de tela donde podr\u00e1s \u00abportear\u00bb todos los regalos de merchandising de los patrocinadores. Es mejor venir ligero y c\u00f3modo porque el d\u00eda es largo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed te daremos bebidas y comida, no hace falta que te vengas con el bocata de chorizo y la bota de vino (aunque en realidad no habr\u00e1 ni chorizo ni vino as\u00ed que si solo comes eso&#8230;).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El domingo s\u00ed que es muy importante que vengas con tu ordenador<\/strong> port\u00e1til al Contributor Day, puesto que se celebran talleres de trabajo. No olvides el cargador.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo debo ir vestido?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nos encantar\u00eda verte vestido de Star Wars, de Star Trek o de cualquier cosa as\u00ed, pero un smoking o un chaqu\u00e9 nos vale igual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un encuentro informal, <strong>ven como m\u00e1s c\u00f3modo te sientas<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfD\u00f3nde puedo aparcar?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfD\u00f3nde?&#8230; Donde cag\u00f3 el conde. No existe ning\u00fan espacio habilitado para como parking cerca. Lo sentimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la <a href=\"https:\/\/2019.irun.wordcamp.org\/localizacion\/\">p\u00e1gina de Localizaci\u00f3n<\/a> tienes informaci\u00f3n sobre nuestras recomendaciones al respecto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfA qu\u00e9 hora voy?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>F\u00e1cil<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El viernes a las 16:15 en la plaza de Urdanibia.<\/li><li>El s\u00e1bado a las 8:15 en la Universidad de Mondragon, porque habr\u00e1 un poco de atasco en la entrada por las acreditaciones.<\/li><li>El domingo a las 10:15 en la Universidad de Mondragon \u00a1y no olvides tu acreditaci\u00f3n!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo debo comportarme en #WCIrun?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existe un <a href=\"https:\/\/2019.irun.wordcamp.org\/codigo-de-conducta\/\">c\u00f3digo de conducta<\/a> que aceptaste al comprar la entrada y que indica que, fundamentalmente, <strong>debes ser respetuoso y colaborativo<\/strong>. Trata de ser amable y de echar un cable cuando veas que es preciso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante que no hagas comentarios ofensivos relacionados con el g\u00e9nero, la orientaci\u00f3n sexual, la raza, la religi\u00f3n o la discapacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En los turnos de preguntas de las ponencias s\u00e9 concreto y pregunta<\/strong> (por eso el turno se llama as\u00ed), no te l\u00edes con reflexiones o valoraciones personales. De esa forma todas las personas que lo deseen tendr\u00e1n su tiempo para preguntar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si crees que algo de lo expuesto por el ponente no ha quedado claro y quieres matizarlo o corregirlo, puedes coment\u00e1rselo despu\u00e9s al propio ponente en el pasillo e incluso presentar tu propia ponencia para WCIrun 2020. \u00a1Nos vendr\u00e1 genial! Pero no uses la ronda de preguntas para ello, por favor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfHabr\u00e1 wifi?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si, gracias a Euskaltel, uno de nuestros partners, vamos a disfrutar de una WiFi todo wapa. High level.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento informaremos de todos los detalles para usarla (sin cosas raras, tranqui).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">No tengo ni idea de WordPress&#8230;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Genial. Este es el evento ideal para empezar a conocerlo. Va a haber mucha gente como t\u00fa. Aprovecha para preguntar y presta mucha atenci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Soy un m\u00e1quina de WordPress&#8230;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Genial. Si eres un experto en WordPress y no has estado nunca en una WordCamp vas a flipar. Ver\u00e1s que hay muchas cosas que se pueden hacer de maneras distintas y descubrir\u00e1s todo lo que mueve la comunidad. Insisto, vas a flipar, crack.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfEl domingo qu\u00e9? \u00bfhay que ir o no?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si te pierdes el domingo, te pierdes una de las cosas m\u00e1s chulas que tienen las WordCamp, el <strong>Contributor Day<\/strong>. Nuestros compa\u00f1eros de marketing han escrito <a rel=\"noreferrer noopener\" aria-label=\"un post muy chulo (opens in a new tab)\" href=\"https:\/\/es.wordpress.org\/2019\/05\/15\/contributorday-wordcamp-irun\/\" target=\"_blank\">un post muy chulo<\/a> para que sepas de qu\u00e9 va el asunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En resumen: S\u00ed, hay que ir.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPuedo ayudar en algo?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed. A lo largo de los 3 d\u00edas surgir\u00e1n cientos de ocasiones para echarnos un cable: moviendo cosas, transmitiendo informaci\u00f3n, coordinando a la gente&#8230; pero sobre todo te necesitamos para tres tareas fundamentales:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Muestra tu mejor cara<\/strong>, se amable y ven con ganas de disfrutar<\/li><li><strong>Si ves a alguien solo, ofr\u00e9cele tu charla y compa\u00f1\u00eda<\/strong>. Este es un evento integrador. Queremos que todo el mundo se sienta c\u00f3modo.<\/li><li><strong>Ay\u00fadanos a ser trending topic<\/strong>. Usa el hashtag oficial #WCIrun en tus redes sociales de forma intensa. Esto visibiliza las WordCamps y nos permite alcanzar acuerdos m\u00e1s favorables con nuestros patrocinadores. Porque sin patrocinadores, no hay WordCamps. <em>Eso es as\u00edn<\/em>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es todo, si tienes cualquier duda puedes hac\u00e9rnosla llegar a trav\u00e9s de los comentarios de este post, de la <a href=\"https:\/\/twitter.com\/wpirun\">cuenta de Twitter<\/a> o mediante el <a href=\"https:\/\/2019.irun.wordcamp.org\/contacto\/\">formulario de contacto<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya no falta casi nada. En unos d\u00edas llega WordCamp Irun y estoy seguro de que muchos de vosotros estar\u00e9is casi tan inquietos como nosotros mismos. Sabemos que algunos os estrenar\u00e9is en una WordCamp en esta ocasi\u00f3n as\u00ed que hemos &hellip; <a href=\"https:\/\/irun.wordcamp.org\/2019\/faq-para-novatos-en-wcirun\/\">Seguir leyendo <span class=\"screen-reader-text\">FAQ para novatos en #WCIrun<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":13668985,"featured_media":1650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[324],"tags":[],"class_list":["post-1646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheIBw-qy","jetpack_featured_media_url":"https:\/\/irun.wordcamp.org\/2019\/files\/2019\/05\/novatos-wordcamp.jpg","_links":{"self":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/1646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/users\/13668985"}],"replies":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/comments?post=1646"}],"version-history":[{"count":8,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/1646\/revisions"}],"predecessor-version":[{"id":1674,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/1646\/revisions\/1674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/media\/1650"}],"wp:attachment":[{"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=1646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/categories?post=1646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2019\/wp-json\/wp\/v2\/tags?post=1646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}