{"id":1728,"date":"2018-05-30T08:00:19","date_gmt":"2018-05-30T06:00:19","guid":{"rendered":"https:\/\/2018.irun.wordcamp.org\/?p=1728"},"modified":"2018-05-29T23:10:19","modified_gmt":"2018-05-29T21:10:19","slug":"gracias-pcbox-irun-patrocinador-bronce-de-wordcamp-irun","status":"publish","type":"post","link":"https:\/\/irun.wordcamp.org\/2018\/gracias-pcbox-irun-patrocinador-bronce-de-wordcamp-irun\/","title":{"rendered":"\u00a1Gracias PCBox Irun! Patrocinador Bronce de WordCamp Irun"},"content":{"rendered":"<p>Para WordCamp Irun siempre ha sido un objetivo clave contar con el apoyo de las empresas m\u00e1s importantes del panorama actual de internet, pero no solo nacionales o internacionales, sino tambi\u00e9n aquellas de nuestro entorno m\u00e1s cercano.<\/p>\n<p>Para nosotros es una alegr\u00eda inmensa contar con el patrocinio Bronce de <a href=\"https:\/\/www.pcbox.com\/tienda-de-informatica\/103\/irun\" rel=\"nofollow\">PCBox Irun<\/a>, que desde el centro mismo de la ciudad, en la calle\u00a0Serapio Mujika 26, ofrece un servicio mod\u00e9lico de venta y atenci\u00f3n t\u00e9cnica a particulares y empresas.<\/p>\n<p>PCBOX Irun dispone de una amplia gama de servicios en tienda: venta e instalaci\u00f3n de software y taller de reparaci\u00f3n de ordenadores, consolas, tablets y smartphones.<\/p>\n<p>Pero no solo ofrecen servicio a usuarios particulares. PCBOX Irun ofrece tambi\u00e9n un servicio profesional con todas las soluciones tecnol\u00f3gicas para tu organizaci\u00f3n. Su equipo especializado te guiar\u00e1 y te proporcionar\u00e1 las soluciones que mejor se adapten a tu negocio. La uni\u00f3n con el grupo TICNOVA, que dispone de m\u00e1s de 300 tiendas en toda Espa\u00f1a, les respalda y les permite brindar un servicio cercano, r\u00e1pido y eficaz con la mayor garant\u00eda profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para WordCamp Irun siempre ha sido un objetivo clave contar con el apoyo de las empresas m\u00e1s importantes del panorama actual de internet, pero no solo nacionales o internacionales, sino tambi\u00e9n aquellas de nuestro entorno m\u00e1s cercano. Para nosotros es una alegr\u00eda inmensa contar con el patrocinio Bronce de PCBox Irun, que desde el centro &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/irun.wordcamp.org\/2018\/gracias-pcbox-irun-patrocinador-bronce-de-wordcamp-irun\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00a1Gracias PCBox Irun! Patrocinador Bronce de WordCamp Irun\u00bb<\/span><\/a><\/p>\n","protected":false},"author":13668985,"featured_media":1732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[324],"tags":[],"class_list":["post-1728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLQe-rS","jetpack_featured_media_url":"https:\/\/irun.wordcamp.org\/2018\/files\/2018\/04\/logo_pcbox_irun_destacado-1.png","_links":{"self":[{"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/13668985"}],"replies":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1728"}],"version-history":[{"count":3,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1728\/revisions"}],"predecessor-version":[{"id":2212,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1728\/revisions\/2212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1732"}],"wp:attachment":[{"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irun.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}